{"id":2610,"date":"2021-01-27T13:44:38","date_gmt":"2021-01-27T13:44:38","guid":{"rendered":"https:\/\/kalikart.com\/chassis-frame\/"},"modified":"2026-05-13T14:26:49","modified_gmt":"2026-05-13T14:26:49","slug":"telai","status":"publish","type":"page","link":"https:\/\/kalikart.com\/en\/telai\/","title":{"rendered":"CHASSIS FRAME"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2610\" class=\"elementor elementor-2610 elementor-85\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0759c1 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a0759c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bbe9d0f\" data-id=\"bbe9d0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30823a5 elementor-widget elementor-widget-heading\" data-id=\"30823a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CHASSIS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-269be36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"269be36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5479dcc\" data-id=\"5479dcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef284ca elementor-widget elementor-widget-text-editor\" data-id=\"ef284ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tThe range of Kal\u00ec Kart chassis was designed to meet the needs of drivers at all levels, from international races to national competitions and single-brand trophies. There are two FIA homologated chassis: the KK2 model made with 30mm tubes and the KK4 model with 32mm tubes. The first one is aimed mainly at direct drive classes, while the 32&#8243; chassis is particularly suitable for shifter categories. The Kal\u00ec Kart range is also completed with the MINI model for the younger categories, the promotional models and for the Rotax DD2 category\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3604a2b e-con-full e-flex e-con e-parent\" data-id=\"3604a2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f82e4a e-con-full e-flex e-con e-child\" data-id=\"5f82e4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bafb782 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"bafb782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/en\/kali-kart-mini\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-4143\" alt=\"\" srcset=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg 2048w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-300x200.jpg 300w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-1024x683.jpg 1024w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-768x512.jpg 768w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/en\/kali-kart-mini\/\">Kal\u00ec Kart MINI<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85016b3 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"85016b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/en\/kali-kart-kk2\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-2048x1365.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-4145\" alt=\"\" srcset=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-2048x1365.jpg 2048w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-300x200.jpg 300w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-1024x683.jpg 1024w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-768x512.jpg 768w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05744-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/en\/kali-kart-kk2\/\">Kal\u00ec Kart KK2<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71067b2 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"71067b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/en\/kali-kart-kk4\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-2048x1365.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-4147\" alt=\"\" srcset=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-2048x1365.jpg 2048w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-300x200.jpg 300w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-1024x683.jpg 1024w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-768x512.jpg 768w, https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05484-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/en\/kali-kart-kk4\/\">Kal\u00ec Kart KK4<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d94056 e-flex e-con-boxed e-con e-parent\" data-id=\"7d94056\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26d444d elementor-widget elementor-widget-heading\" data-id=\"26d444d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Are you interested in one of our karts?\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a26bfce elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a26bfce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/dealer\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FIND THE DEALER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CHASSIS The range of Kal\u00ec Kart chassis was designed to meet the needs of drivers at all levels, from international races to national competitions and single-brand trophies. There are two FIA homologated chassis: the KK2 model made with 30mm tubes and the KK4 model with 32mm tubes. The first one is aimed mainly at direct [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2610","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kali Kart - CHASSIS FRAME<\/title>\n<meta name=\"description\" content=\"Kali Kart - CHASSIS FRAME\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kalikart.com\/en\/telai\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kali Kart - CHASSIS FRAME\" \/>\n<meta property=\"og:description\" content=\"Kali Kart - CHASSIS FRAME\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kalikart.com\/en\/telai\/\" \/>\n<meta property=\"og:site_name\" content=\"Kali Kart\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kalikartofficial?locale=it_IT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:26:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kalikart.com\/en\/telai\/\",\"url\":\"https:\/\/kalikart.com\/en\/telai\/\",\"name\":\"Kali Kart - CHASSIS FRAME\",\"isPartOf\":{\"@id\":\"https:\/\/kalikart.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kalikart.com\/en\/telai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kalikart.com\/en\/telai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg\",\"datePublished\":\"2021-01-27T13:44:38+00:00\",\"dateModified\":\"2026-05-13T14:26:49+00:00\",\"description\":\"Kali Kart - CHASSIS FRAME\",\"breadcrumb\":{\"@id\":\"https:\/\/kalikart.com\/en\/telai\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kalikart.com\/en\/telai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kalikart.com\/en\/telai\/#primaryimage\",\"url\":\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg\",\"contentUrl\":\"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kalikart.com\/en\/telai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kalikart.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHASSIS FRAME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kalikart.com\/#website\",\"url\":\"https:\/\/kalikart.com\/\",\"name\":\"Kal\u00ec Kart\",\"description\":\"produzione Kart racing\",\"publisher\":{\"@id\":\"https:\/\/kalikart.com\/#organization\"},\"alternateName\":\"Kal\u00ec Kart\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kalikart.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kalikart.com\/#organization\",\"name\":\"Kal\u00ec Kart\",\"url\":\"https:\/\/kalikart.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kalikart.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kalikart.com\/wp-content\/uploads\/2024\/02\/kalikart_logo.svg\",\"contentUrl\":\"https:\/\/kalikart.com\/wp-content\/uploads\/2024\/02\/kalikart_logo.svg\",\"width\":205,\"height\":41,\"caption\":\"Kal\u00ec Kart\"},\"image\":{\"@id\":\"https:\/\/kalikart.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kalikartofficial?locale=it_IT\",\"https:\/\/www.instagram.com\/kalikart_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kali Kart - CHASSIS FRAME","description":"Kali Kart - CHASSIS FRAME","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kalikart.com\/en\/telai\/","og_locale":"en_US","og_type":"article","og_title":"Kali Kart - CHASSIS FRAME","og_description":"Kali Kart - CHASSIS FRAME","og_url":"https:\/\/kalikart.com\/en\/telai\/","og_site_name":"Kali Kart","article_publisher":"https:\/\/www.facebook.com\/kalikartofficial?locale=it_IT","article_modified_time":"2026-05-13T14:26:49+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kalikart.com\/en\/telai\/","url":"https:\/\/kalikart.com\/en\/telai\/","name":"Kali Kart - CHASSIS FRAME","isPartOf":{"@id":"https:\/\/kalikart.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kalikart.com\/en\/telai\/#primaryimage"},"image":{"@id":"https:\/\/kalikart.com\/en\/telai\/#primaryimage"},"thumbnailUrl":"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg","datePublished":"2021-01-27T13:44:38+00:00","dateModified":"2026-05-13T14:26:49+00:00","description":"Kali Kart - CHASSIS FRAME","breadcrumb":{"@id":"https:\/\/kalikart.com\/en\/telai\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kalikart.com\/en\/telai\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kalikart.com\/en\/telai\/#primaryimage","url":"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg","contentUrl":"https:\/\/kalikart.com\/wp-content\/uploads\/2026\/05\/LOR05071-2048x1365.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/kalikart.com\/en\/telai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kalikart.com\/en\/"},{"@type":"ListItem","position":2,"name":"CHASSIS FRAME"}]},{"@type":"WebSite","@id":"https:\/\/kalikart.com\/#website","url":"https:\/\/kalikart.com\/","name":"Kal\u00ec Kart","description":"produzione Kart racing","publisher":{"@id":"https:\/\/kalikart.com\/#organization"},"alternateName":"Kal\u00ec Kart","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kalikart.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kalikart.com\/#organization","name":"Kal\u00ec Kart","url":"https:\/\/kalikart.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kalikart.com\/#\/schema\/logo\/image\/","url":"https:\/\/kalikart.com\/wp-content\/uploads\/2024\/02\/kalikart_logo.svg","contentUrl":"https:\/\/kalikart.com\/wp-content\/uploads\/2024\/02\/kalikart_logo.svg","width":205,"height":41,"caption":"Kal\u00ec Kart"},"image":{"@id":"https:\/\/kalikart.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kalikartofficial?locale=it_IT","https:\/\/www.instagram.com\/kalikart_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/pages\/2610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/comments?post=2610"}],"version-history":[{"count":26,"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/pages\/2610\/revisions"}],"predecessor-version":[{"id":4169,"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/pages\/2610\/revisions\/4169"}],"wp:attachment":[{"href":"https:\/\/kalikart.com\/en\/wp-json\/wp\/v2\/media?parent=2610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}